{"id":1512,"date":"2019-12-12T20:34:43","date_gmt":"2019-12-12T20:34:43","guid":{"rendered":"http:\/\/btselfstoragemobile.com\/?page_id=1512"},"modified":"2026-04-05T13:16:16","modified_gmt":"2026-04-05T13:16:16","slug":"unit-sizes-prices","status":"publish","type":"page","link":"http:\/\/btselfstoragemobile.com\/index.php\/unit-sizes-prices\/","title":{"rendered":"Unit-sizes-prices"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"> <strong>B&amp;T Self Storage of Bloomingdale, NJ<\/strong> <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>24-hour access, security monitors.<\/strong><\/h3>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">We are a full-service, 24 hour Secure facility. Our courteous and friendly staff will help you select the unit most appropriate for your storage and transporting needs. You can NOW <a href=\"https:\/\/www.uhaul.com\/Locations\/Self-Storage-near-Bloomingdale-NJ-07403\/1001482\/\" target=\"_blank\" rel=\"noreferrer noopener\">VIEW RATES \/ RESERVE ONLINE<\/a> at B &amp; T Self Storage, we are a full-service, fenced-in, 24 hour access facility with self storage units of all sizes. Instead of leasing more office space, reduce your business costs by renting a storage unit with us.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><h2 id=\"tablepress-1-name\" class=\"tablepress-table-name tablepress-table-name-id-1\">Unit Rates<\/h2>\n\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\" aria-labelledby=\"tablepress-1-name\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\">5 x 10<\/td><td class=\"column-2\">Call for Rates \/ Availability <\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">10 x 10<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">10 x 15<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">10 x 20<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">10 x 25<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">10 x 30<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">10 x 40<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">20 x 20<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">600 sq ft<\/td><td class=\"column-2\">Call for Rates \/ Availability<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache --><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"366\" data-id=\"1534\" src=\"https:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2019\/10\/Nbanner-3.jpg\" alt=\"\" class=\"wp-image-1534\" srcset=\"http:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2019\/10\/Nbanner-3.jpg 600w, http:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2019\/10\/Nbanner-3-300x183.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"400\" data-id=\"1646\" src=\"https:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2024\/11\/dealership-pics-007-640x400-1.jpg\" alt=\"\" class=\"wp-image-1646\" srcset=\"http:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2024\/11\/dealership-pics-007-640x400-1.jpg 640w, http:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2024\/11\/dealership-pics-007-640x400-1-300x188.jpg 300w, http:\/\/btselfstoragemobile.com\/wp-content\/uploads\/2024\/11\/dealership-pics-007-640x400-1-480x300.jpg 480w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Storage Unit sizes &#038; Prices<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1512","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/pages\/1512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":8,"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/pages\/1512\/revisions"}],"predecessor-version":[{"id":1649,"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/pages\/1512\/revisions\/1649"}],"wp:attachment":[{"href":"http:\/\/btselfstoragemobile.com\/index.php\/wp-json\/wp\/v2\/media?parent=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}